{"id":979,"date":"2024-01-25T23:57:50","date_gmt":"2024-01-26T05:57:50","guid":{"rendered":"http:\/\/data.sedema.cdmx.gob.mx:9000\/bosquedechapultepec\/?post_type=espacios&#038;p=979"},"modified":"2024-09-03T17:41:52","modified_gmt":"2024-09-03T22:41:52","slug":"centro-hipico-de-la-ciudad-de-mexico","status":"publish","type":"espacios","link":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/espacios\/centro-hipico-de-la-ciudad-de-mexico\/","title":{"rendered":"Centro H\u00edpico de la Ciudad de M\u00e9xico\u00a0"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading sm:text-3xl md:text-3xl lg:text-4xl xl:text-4xl\"><strong>Centro H\u00edpico de la Ciudad de M\u00e9xico<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>El Centro H\u00edpico de la Ciudad de M\u00e9xico es un espacio donde se vive el apasionante mundo de la equitaci\u00f3n y el tiro con arco. <\/p>\n\n\n\n<p>Desde 1973, este club ofrece 40 hect\u00e1reas para aprender a montar a caballo y perfeccionar las habilidades en la arquer\u00eda. <br><br><strong>Horario:<\/strong><br>Martes a domingo de 9:00 a 16:00 horas<br><br><strong>Costo:<\/strong><br>Costo sujeto a la programaci\u00f3n<br><br><strong>Ubicaci\u00f3n:<\/strong><br><a href=\"https:\/\/maps.app.goo.gl\/SRirVVBcyj897oFk8\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Avenida Bosques, Tercera Secci\u00f3n del Bosque de Chapultepec<\/mark><\/a><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false},"categories":[5,32,6],"tags":[63],"class_list":["post-979","espacios","type-espacios","status-publish","format-standard","hentry","category-espacios","category-recintos-culturales-tercera-seccion","category-tercera-seccion","tag-chapultepec-tercera-seccion"],"acf":[],"_links":{"self":[{"href":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/wp-json\/wp\/v2\/espacios\/979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/wp-json\/wp\/v2\/espacios"}],"about":[{"href":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/wp-json\/wp\/v2\/types\/espacios"}],"wp:attachment":[{"href":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/wp-json\/wp\/v2\/media?parent=979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/wp-json\/wp\/v2\/categories?post=979"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/wp-json\/wp\/v2\/tags?post=979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}