{"id":877,"date":"2024-01-25T21:29:17","date_gmt":"2024-01-26T03:29:17","guid":{"rendered":"http:\/\/data.sedema.cdmx.gob.mx:9000\/bosquedechapultepec\/?post_type=espacios&#038;p=877"},"modified":"2025-07-23T19:36:05","modified_gmt":"2025-07-24T00:36:05","slug":"la-hormiga","status":"publish","type":"espacios","link":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/espacios\/la-hormiga\/","title":{"rendered":"Parque Infantil La Hormiga"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading sm:text-3xl md:text-3xl lg:text-4xl xl:text-4xl\"><strong>Parque Infantil \u201cLa Hormiga\u201d<\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>El Parque Infantil La Hormiga es un espacio al aire libre donde los m\u00e1s peque\u00f1os del hogar pueden disfrutar de juegos infantiles, \u00e1reas verdes y una amplia variedad de actividades. Antigua parte de la residencia oficial de Los Pinos, este parque de 40,000 m\u00b2 fue renovado y abierto al p\u00fablico en diciembre de 2016.<br><br><strong>Horario:<\/strong><br>Martes a domingo de 09:00 a 17:00 horas.<br><br><strong>Costo:<\/strong><br>Entrada libre<br><br><strong>Ubicaci\u00f3n:<\/strong><br><a href=\"https:\/\/maps.app.goo.gl\/QusYTVtUxv5Yvo5t7\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Molino del Rey 1, San Miguel Chapultepec, Primera Secci\u00f3n.<\/mark><\/a><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">DISPOSICIONES PARA EL INGRESO Y PERMANENCIA<\/h4>\n\n\n\n<h3 class=\"wp-block-heading\">PARQUE INFANTIL LA HORMIGA<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Este espacio p\u00fablico est\u00e1 destinado \u00fanicamente para el disfrute y convivencia de las ni\u00f1as y ni\u00f1os, acompa\u00f1ados de una persona adulta;<\/li>\n\n\n\n<li>En este espacio se implementa la estrategia BASURA CERO para la reducci\u00f3n de residuos en la Ciudad de M\u00e9xico, por lo que no debes generar o dejar residuos dentro del parque;<\/li>\n\n\n\n<li>Est\u00e1 prohibido el ingreso de bicicletas, por lo que se deber\u00e1n aparcar en los biciestacionamientos existentes;<\/li>\n\n\n\n<li>Se proh\u00edbe a los visitantes introducir animales de compa\u00f1\u00eda de cualquier especie;<\/li>\n\n\n\n<li>Se proh\u00edbe la introducci\u00f3n, consumo y venta de todo tipo de bebidas alcoh\u00f3licas y no se permitir\u00e1 la entrada y\/o permanencia a personas en estado de ebriedad o bajo la influencia de estupefacientes o psicotr\u00f3picos;<\/li>\n\n\n\n<li>Se proh\u00edbe encender fogatas, braseros, parrillas el\u00e9ctricas y hornillas de cualquier tipo as\u00ed como la posesi\u00f3n y uso de explosivos, cohetes y cualquier sustancia qu\u00edmica o inflamable que atente contra la integridad f\u00edsica o ambiental de las personas y\/o de los bienes e instalaciones del parque;<\/li>\n\n\n\n<li>Queda prohibido, el uso de hamacas, carpas, lonas; arrancar, cortar, sacar o de cualquier forma da\u00f1ar las plantas, o \u00e1rboles, as\u00ed como molestar, capturar, o de cualquier forma da\u00f1ar cualquier animal que se encuentre dentro del parque;<\/li>\n\n\n\n<li>Los visitantes deber\u00e1n conservar y respetar las \u00e1reas verdes, as\u00ed como el mobiliario e instalaciones del parque;<\/li>\n\n\n\n<li>Aquella persona que cometa una infracci\u00f3n contra la dignidad y la tranquilidad de las personas, la seguridad ciudadana, contra el entorno urbano de la Ciudad, previstas en la Ley de Cultura C\u00edvica de la Ciudad de M\u00e9xico, ser\u00e1 puesta a disposici\u00f3n del Juzgado C\u00edvico correspondiente;<\/li>\n\n\n\n<li>En todo lo que no est\u00e9 previsto en estas disposiciones, se aplicar\u00e1n los ordenamientos jur\u00eddicos que regulen los casos de que se trate.<\/li>\n<\/ul>\n\n\n\n<p>La Direcci\u00f3n Ejecutiva del Bosque de Chapultepec no ser\u00e1 responsable por la p\u00e9rdida, robo o extrav\u00edo de bienes u objetos de valor o personales dentro del parque.<\/p>\n\n\n\n<p>Lo anterior con fundamento en el art\u00edculo 4\u00ba p\u00e1rrafo d\u00e9cimo de la Constituci\u00f3n Pol\u00edtica de los Estados Unidos Mexicanos; 1, 3\u00aa, 4\u00ba Apartado B numeral 4, 11 Apartado D numerales 1 y 2, 33 de la Constituci\u00f3n Pol\u00edtica de la Ciudad de M\u00e9xico; 7\u00aa, 13 fracci\u00f3n XII y 62 de Ley de los Derechos de Ni\u00f1as, Ni\u00f1os y Adolescentes de la Ciudad de M\u00e9xico; II fracci\u00f3n I, 12, 16 fracci\u00f3n X y 18 p\u00e1rrafo segundo de la Ley Org\u00e1nica del Poder Ejecutivo y de la Administraci\u00f3n P\u00fablica de la Ciudad de M\u00e9xico; 3\u00aa fracci\u00f3n I, 7\u00aa fracci\u00f3n X Inciso F) Numeral 1), 41 fracci\u00f3n XVIII y 190 Bis fracci\u00f3n VI del Reglamento Interior del Poder Ejecutivo y de la Administraci\u00f3n P\u00fablica de la Ciudad de M\u00e9xico.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false},"categories":[5,44,3],"tags":[],"class_list":["post-877","espacios","type-espacios","status-publish","format-standard","hentry","category-espacios","category-parques-y-areas-recreativas-primera-seccion","category-primera-seccion"],"acf":[],"_links":{"self":[{"href":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/wp-json\/wp\/v2\/espacios\/877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/wp-json\/wp\/v2\/espacios"}],"about":[{"href":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/wp-json\/wp\/v2\/types\/espacios"}],"wp:attachment":[{"href":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/wp-json\/wp\/v2\/media?parent=877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/wp-json\/wp\/v2\/categories?post=877"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/wp-json\/wp\/v2\/tags?post=877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}