{"id":1431,"date":"2024-02-15T14:28:46","date_gmt":"2024-02-15T20:28:46","guid":{"rendered":"http:\/\/data.sedema.cdmx.gob.mx:9000\/bosquedechapultepec\/?post_type=espacios&#038;p=1431"},"modified":"2025-02-21T15:04:08","modified_gmt":"2025-02-21T21:04:08","slug":"biblioteca-de-semillas","status":"publish","type":"espacios","link":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/espacios\/biblioteca-de-semillas\/","title":{"rendered":"Biblioteca de Semillas"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading sm:text-3xl md:text-3xl lg:text-4xl xl:text-4xl\"><strong><strong>Biblioteca de semillas<\/strong><\/strong><\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La Biblioteca de Semillas y Taller de Artes, Oficios y T\u00e9cnicas para la Restauraci\u00f3n Ambiental es un espacio donde se impulsara la integraci\u00f3n del sentido de comunidad a trav\u00e9s de las pr\u00e1cticas asociadas con la horticultura a trav\u00e9s del acopio, almacenamiento, conservaci\u00f3n y entendimiento del manejo de semillas de vegetaci\u00f3n nativa.<\/p>\n\n\n\n<p><br><br><strong>Horario:<\/strong><br>Por definir<\/p>\n\n\n\n<p><strong>Ubicaci\u00f3n: <\/strong><br><a href=\"https:\/\/maps.app.goo.gl\/cWgY3YQvQKBZ6Z787\" data-type=\"link\" data-id=\"https:\/\/maps.app.goo.gl\/cWgY3YQvQKBZ6Z787\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Av. Jos\u00e9 Mar\u00eda Velasco s\/n, Tercera Secci\u00f3n del Bosque de Chapultepec<\/mark><\/a><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false},"categories":[5,32,6],"tags":[63,94,61],"class_list":["post-1431","espacios","type-espacios","status-publish","format-standard","hentry","category-espacios","category-recintos-culturales-tercera-seccion","category-tercera-seccion","tag-chapultepec-tercera-seccion","tag-lectura","tag-tercera-seccion"],"acf":[],"_links":{"self":[{"href":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/wp-json\/wp\/v2\/espacios\/1431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/wp-json\/wp\/v2\/espacios"}],"about":[{"href":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/wp-json\/wp\/v2\/types\/espacios"}],"wp:attachment":[{"href":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/wp-json\/wp\/v2\/media?parent=1431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/wp-json\/wp\/v2\/categories?post=1431"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/bosquedechapultepec.mx:9000\/bosquedechapultepec\/wp-json\/wp\/v2\/tags?post=1431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}